{"id":20295,"date":"2026-01-14T15:26:00","date_gmt":"2026-01-14T14:26:00","guid":{"rendered":"https:\/\/www.csfconsulting.es\/?p=20295"},"modified":"2026-01-14T15:26:00","modified_gmt":"2026-01-14T14:26:00","slug":"aviso-de-presentacion-de-modelos-y-plazos-de-declaracion-irpf-iva-sociedades-y-otras-obligaciones-informativas-enero-y-febrero-2026","status":"publish","type":"post","link":"https:\/\/www.csfconsulting.es\/fr\/aviso-de-presentacion-de-modelos-y-plazos-de-declaracion-irpf-iva-sociedades-y-otras-obligaciones-informativas-enero-y-febrero-2026\/","title":{"rendered":"Aviso de presentaci\u00f3n de modelos y plazos de declaraci\u00f3n. IRPF, IVA, Sociedades y otras obligaciones informativas. Enero y Febrero 2026"},"content":{"rendered":"<div class=\"content\">\n<h4>El pr\u00f3ximo d\u00eda 20 de enero es la fecha l\u00edmite para presentar y en su caso proceder al ingreso del 4 TRIMESTRE del 2025 correspondiente a las retenciones e ingresos a cuenta de Renta y Sociedades, y el d\u00eda 30 de enero y 2 de febrero las fecha l\u00edmites para presenta res\u00famenes anuales del IVA y Retenciones del a\u00f1o 2025, respectivamente. Sin perjuicio de los plazos de presentaci\u00f3n de autoliquidaciones con domiciliaci\u00f3n bancaria\u2026<\/h4>\n<p>Le recordamos que <strong>el pr\u00f3ximo d\u00eda 20 de enero<\/strong> es la fecha l\u00edmite para presentar y en su caso proceder al ingreso del <strong>4 TRIMESTRE del 2025 <\/strong>correspondiente a las <strong>retenciones e ingresos a cuenta de Renta y Sociedades <\/strong>correspondientes a rendimientos del trabajo, actividades econ\u00f3micas, premios y determinadas ganancias patrimoniales e imputaciones de renta, ganancias derivadas de acciones y participaciones de las instituciones de inversi\u00f3n colectiva, rentas de arrendamiento de inmuebles urbanos, capital mobiliario, personas autorizadas y saldos en cuentas (Modelos 111, 115, 117, 123, 124, 126, 128, 136, 210, 216).<\/p>\n<p>Para las grandes empresas:<\/p>\n<ul>\n<li>Diciembre 2025. Grandes empresas: 111, 115, 117, 123, 124, 126, 128, 216, 230<\/li>\n<\/ul>\n<p>Tambi\u00e9n hasta el <strong>d\u00eda 20 de ENERO<\/strong> tiene de plazo para presentar el Modelo 039 sobre Comunicaci\u00f3n de datos (comunicaci\u00f3n de incorporaciones en el mes de diciembre), relativa al <strong>r\u00e9gimen especial del grupo de entidades en el IVA<\/strong>.<\/p>\n<p>Asimismo, le recordamos que el <strong>d\u00eda 30 ENERO <\/strong>es la fecha l\u00edmite para presentar y en su caso proceder al ingreso del <strong>4\u00ba TRIMESTRE 2025 <\/strong>correspondiente al\u00a0 <strong>IVA<\/strong> (entre otros, el Modelo 303 de autoliquidaci\u00f3n del IVA y el modelo 349 Declaraci\u00f3n recapitulativa de operaciones intracomunitarias) y el <strong>Pago fraccionado del<\/strong> <strong>IRPF <\/strong>en relaci\u00f3n a las actividades empresariales y profesionales (Modelos 130 y 131).<\/p>\n<p>Hasta <strong>esa fecha <\/strong>tambi\u00e9n se podr\u00e1 presentar:<\/p>\n<ul>\n<li>Solicitud de devoluci\u00f3n de cuotas reembolsadas a viajeros por empresarios en recargo de equivalencia: 308<\/li>\n<li>Regularizaci\u00f3n de las proporciones de tributaci\u00f3n de los periodos de liquidaci\u00f3n anteriores al inicio de la realizaci\u00f3n habitual de entregas de bienes o prestaciones de servicio: 318<\/li>\n<li>Reintegro de compensaciones en el r\u00e9gimen especial de la agricultura, ganader\u00eda y pesca: 341<\/li>\n<li>Opci\u00f3n o revocaci\u00f3n de la aplicaci\u00f3n de la prorrata especial para 2029 y siguientes, si se inici\u00f3 la actividad en el \u00faltimo trimestre de 2025: 036\/037<\/li>\n<\/ul>\n<p>Tambi\u00e9n se ha de presentar hasta <strong>el d\u00eda 31 de ENERO<\/strong> el <strong>RESUMEN ANUAL del IVA 2025 <\/strong>(Modelo 390).<\/p>\n<p>Recuerde tambi\u00e9n que el <strong>d\u00eda 2 de FEBRERO<\/strong> es la fecha l\u00edmite para presentar el <strong>RESUMEN ANUAL<\/strong> <strong>2025<\/strong> <strong>de<\/strong> <strong>retenciones e ingresos a cuenta de Renta y Sociedades: <\/strong>rendimientos del trabajo, actividades econ\u00f3micas, premios y determinadas ganancias patrimoniales e imputaciones de renta, ganancias derivadas de acciones y participaciones de las instituciones de inversi\u00f3n colectiva, rentas de arrendamiento de inmuebles urbanos, capital mobiliario, personas autorizadas y saldos en cuentas<strong> (<\/strong>Modelos 180,188, 190, 193,193-S, 194, 196 y 270).<\/p>\n<p><strong>Tambi\u00e9n hasta el 2 de febrero deber\u00e1 presentar: <\/strong><\/p>\n<ul>\n<li>IRPF. Renuncia o revocaci\u00f3n estimaci\u00f3n directa simplificada y estimaci\u00f3n objetiva para 2026 y sucesivos: 036\/037<\/li>\n<li>IVA. Renuncia o revocaci\u00f3n reg\u00edmenes simplificado y agricultura, ganader\u00eda y pesca para 2026 y sucesivos: 036\/037.<\/li>\n<li>Plazo extraordinario para la solicitud de baja. Registro de devoluci\u00f3n mensual: 036<\/li>\n<li>SII. Plazo extraordinario para la renuncia a la llevanza electr\u00f3nica de los libros registro: 036<\/li>\n<li>Solicitud de aplicaci\u00f3n del porcentaje provisional de deducci\u00f3n distinto del fijado como definitivo en el a\u00f1o precedente: sin modelo<\/li>\n<\/ul>\n<p><strong>Plazos de presentaci\u00f3n de autoliquidaciones con domiciliaci\u00f3n bancaria<\/strong><\/p>\n<p>El plazo de presentaci\u00f3n de\u00a0<strong>autoliquidaciones<\/strong>\u00a0con<strong>\u00a0domiciliaci\u00f3n bancaria<\/strong>\u00a0va a depender del fin del plazo de presentaci\u00f3n de cada modelo. As\u00ed, si el vencimiento del plazo de presentaci\u00f3n coincide con un d\u00eda inh\u00e1bil, el plazo finaliza el primer d\u00eda h\u00e1bil siguiente y el\u00a0plazo de domiciliaci\u00f3n bancaria se ampliar\u00e1 con car\u00e1cter general el mismo n\u00famero de d\u00edas que resulte ampliado el plazo de presentaci\u00f3n de dicha declaraci\u00f3n.<\/p>\n<p>En este <a class=\"external\" href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/ayuda\/calendario-contribuyente\/calendario-contribuyente-2026\/calendario-anual.html\" target=\"_blank\" rel=\"external noopener\">enlace<\/a>, se indican los plazos generales y de domiciliaci\u00f3n bancaria para cada modelo, correspondientes al a\u00f1o 2026<\/p>\n<p>Aprovechamos la ocasi\u00f3n para recodarles <strong>otras obligaciones (declaraciones informativas)<\/strong> <strong>hasta el 2 de febrero:<\/strong><\/p>\n<p>Declaraci\u00f3n informativa de certificaciones individuales emitidas a los socios o part\u00edcipes de entidades de nueva o reciente creaci\u00f3n<\/p>\n<ul>\n<li>Resumen anual 2025: 165<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa anual de imposiciones, disposiciones de fondos y de los cobros de cualquier documento<\/p>\n<ul>\n<li>A\u00f1o 2025: 171<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa sobre saldos en monedas virtuales y sobre operaciones con monedas virtuales<\/p>\n<ul>\n<li>A\u00f1o 2025: 172, 173<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de pr\u00e9stamos y cr\u00e9ditos y otras operaciones financieras relacionadas con bienes inmuebles<\/p>\n<ul>\n<li>Declaraci\u00f3n anual 2025: 181<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de donativos, donaciones y aportaciones recibidas y disposiciones realizadas<\/p>\n<ul>\n<li>Declaraci\u00f3n anual 2025: 182<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de entidades en r\u00e9gimen de atribuci\u00f3n de rentas<\/p>\n<ul>\n<li>A\u00f1o 2025: 184<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de adquisiciones y enajenaciones de acciones y participaciones en Instituciones de Inversi\u00f3n Colectiva<\/p>\n<ul>\n<li>Declaraci\u00f3n anual 2025: 187<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa por gastos en guarder\u00edas o centros de educaci\u00f3n infantil autorizados<\/p>\n<ul>\n<li>Declaraci\u00f3n anual 2025: 233<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de actualizaci\u00f3n de determinados mecanismos transfronterizos comercializables<\/p>\n<ul>\n<li>Cuarto trimestre 2025: 235<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa para la comunicaci\u00f3n de informaci\u00f3n por parte de operadores de plataformas<\/p>\n<ul>\n<li>A\u00f1o 2025: 238<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa trimestral de operaciones de comercio de bienes corporales realizadas en la zona especial canaria sin que las mercanc\u00edas transiten por territorio canario<\/p>\n<ul>\n<li>Cuarto trimestre 2025: 281<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa de cuentas de no residentes<\/p>\n<ul>\n<li>A\u00f1o 2025: 291<\/li>\n<\/ul>\n<p>Planes, fondos de pensiones, sistemas alternativos, mutualidades de previsi\u00f3n social, planes de previsi\u00f3n asegurados, planes individuales de ahorro sistem\u00e1tico, planes de previsi\u00f3n social empresarial y seguros de dependencia<\/p>\n<ul>\n<li>Declaraci\u00f3n anual 2025: 345<\/li>\n<\/ul>\n<p>Declaraci\u00f3n informativa sobre pagos transfronterizos<\/p>\n<ul>\n<li>Cuarto trimestre 2025:379<\/li>\n<\/ul>\n<p>Por este motivo, les rogamos que, en el menor plazo posible,\u00a0 nos faciliten toda la documentaci\u00f3n as\u00ed como aquellos datos que les solicitamos para poder realizar la confecci\u00f3n\u00a0 y presentaci\u00f3n de dichas declaraciones.<\/p>\n<p>Sin otro particular, reciba un cordial saludo<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo d\u00eda 20 de enero es la fecha l\u00edmite para presentar y en su caso proceder al ingreso del 4 TRIMESTRE del 2025 correspondiente a las retenciones e ingresos a cuenta de Renta y Sociedades, y el d\u00eda 30 de enero y 2 de febrero las fecha l\u00edmites para presenta res\u00famenes anuales del IVA&hellip;<\/p>\n","protected":false},"author":7,"featured_media":20296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/posts\/20295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/comments?post=20295"}],"version-history":[{"count":11,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/posts\/20295\/revisions"}],"predecessor-version":[{"id":20307,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/posts\/20295\/revisions\/20307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/media\/20296"}],"wp:attachment":[{"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/media?parent=20295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/categories?post=20295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csfconsulting.es\/fr\/wp-json\/wp\/v2\/tags?post=20295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}